{"id":594,"date":"2019-08-10T09:42:14","date_gmt":"2019-08-10T09:42:14","guid":{"rendered":"https:\/\/www.dfhydraulicscissorlift.com\/?p=594"},"modified":"2019-08-10T09:42:14","modified_gmt":"2019-08-10T09:42:14","slug":"tracked-scissor-lift","status":"publish","type":"post","link":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/tracked-scissor-lift\/","title":{"rendered":"Ciseaux de levage trac\u00e9s"},"content":{"rendered":"<p>Pont \u00e9l\u00e9vateur \u00e0 ciseaux sur chenilles (pont \u00e9l\u00e9vateur \u00e0 ciseaux hors route)\uff1a<\/p>\r\n<p>L'\u00e9l\u00e9vateur \u00e0 ciseaux automoteur sur chenilles peut \u00eatre d\u00e9plac\u00e9 et utilis\u00e9 sur la surface de la table \u00e0 l'\u00e9tat de levage, et le fonctionnement et l'utilisation sont plus pratiques et plus flexibles. Une seule personne peut faire fonctionner la machine pour effectuer le levage, l'avance, le recul, la direction et autres op\u00e9rations similaires dans une op\u00e9ration \u00e0 haute altitude. La plate-forme hydraulique am\u00e9liore consid\u00e9rablement l'efficacit\u00e9 du travail et r\u00e9duit le nombre d'op\u00e9rateurs et l'intensit\u00e9 du travail. L'\u00e9l\u00e9vateur \u00e0 ciseaux \u00e9lectrique est particuli\u00e8rement adapt\u00e9 \u00e0 une large gamme d'op\u00e9rations continues en haute altitude, comme les terminaux d'a\u00e9roport, les gares, les terminaux, les centres commerciaux, les stades, les propri\u00e9t\u00e9s r\u00e9sidentielles, les usines et les mines.<\/p>\r\n<div class=\"grid imges_more\">\r\n<div class=\"grid-6\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.dfhydraulicscissorlift.com\/wp-content\/uploads\/2019\/08\/hydraulic-track-scissor-lift.jpg\" alt=\"\" class=\"alignnone wp-image-595 size-full\" width=\"700\" height=\"700\" title=\"\" srcset=\"https:\/\/www.dfhydraulicscissorlift.com\/wp-content\/uploads\/2019\/08\/hydraulic-track-scissor-lift.jpg 700w, https:\/\/www.dfhydraulicscissorlift.com\/wp-content\/uploads\/2019\/08\/hydraulic-track-scissor-lift-150x150.jpg 150w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div>\r\n<div class=\"grid-4\">\r\n<p>Charge nominale 300 (kg)<\/p>\r\n<p>Hauteur maximale : 10m<\/p>\r\n<p>Poids de la machine : 2880 (kg)<\/p>\r\n<p>Alimentation \u00e9lectrique : batterie ou diesel<\/p>\r\n<p>Lever le temps : 35s<\/p>\r\n<p>Certification :<\/p>\r\n<p>CE ISO9001 SGS<\/p>\r\n<p>Mat\u00e9riel :<\/p>\r\n<p>Structure en acier \u00e0 haute r\u00e9sistance<\/p>\r\n<p>Garantie :<\/p>\r\n<p>24 mois<\/p>\r\n<\/div>\r\n<\/div>\r\n<p>&nbsp;<\/p>\r\n<p>\u00c9l\u00e9vateur \u00e0 ciseaux sur chenilles parameter\uff1a<\/p>\r\n<div class=\"custom_tables\"><table>\n<tbody>\n<tr>\n<td width=\"110\">\n<p>mod\u00e8le<\/p>\n<\/td>\n<td width=\"107\">\n<p>taille de la table<\/p>\n<\/td>\n<td width=\"147\">\n<p>Dimensions g\u00e9n\u00e9rales<\/p>\n<\/td>\n<td width=\"90\">\n<p>Hauteur de la plate-forme<\/p>\n<\/td>\n<td width=\"71\">\n<p>charger<\/p>\n<\/td>\n<td width=\"131\">\n<p>Plate-forme en surplomb<\/p>\n<\/td>\n<td width=\"71\">\n<p>poids<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"110\">\n<p>GTJZ06<\/p>\n<\/td>\n<td width=\"107\">\n<p>2.26\u00d70.81<\/p>\n<\/td>\n<td width=\"147\">\n<p>2.655\u00d71.35\u00d72.33<\/p>\n<\/td>\n<td width=\"90\">\n<p>6M<\/p>\n<\/td>\n<td width=\"71\">\n<p>300KG<\/p>\n<\/td>\n<td width=\"131\">\n<p>0.9<\/p>\n<\/td>\n<td width=\"71\">\n<p>2750kg<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"110\">\n<p>GTJZ08<\/p>\n<\/td>\n<td width=\"107\">\n<p>2.26\u00d70.81<\/p>\n<\/td>\n<td width=\"147\">\n<p>2.655\u00d71.35\u00d72.48<\/p>\n<\/td>\n<td width=\"90\">\n<p>8M<\/p>\n<\/td>\n<td width=\"71\">\n<p>300KG<\/p>\n<\/td>\n<td width=\"131\">\n<p>0.9<\/p>\n<\/td>\n<td width=\"71\">\n<p>2880 kg<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"110\">\n<p>GTJZ10<\/p>\n<\/td>\n<td width=\"107\">\n<p>2.26\u00d70.81<\/p>\n<\/td>\n<td width=\"147\">\n<p>2.655\u00d71.55\u00d72.61<\/p>\n<\/td>\n<td width=\"90\">\n<p>10M<\/p>\n<\/td>\n<td width=\"71\">\n<p>300KG<\/p>\n<\/td>\n<td width=\"131\">\n<p>0.9<\/p>\n<\/td>\n<td width=\"71\">\n<p>3020KG<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\r\n<p>Produits phares :<\/p>\r\n<p>Le ch\u00e2ssis \u00e0 chenilles a une grande adaptabilit\u00e9, particuli\u00e8rement adapt\u00e9 aux sols boueux, meubles et autres, et peut pivoter de 360 degr\u00e9s in situ. Changement de vitesse sans \u00e0-coups. Toute l'action est contr\u00f4l\u00e9e par des poign\u00e9es de commande sur le banc de travail. Le moteur est \u00e0 vitesse variable en continu, ce qui prolonge efficacement la dur\u00e9e de vie de la batterie et du moteur.<\/p>\r\n<p>Avantages<\/p>\r\n<p>&nbsp;<\/p>\r\n<p>1L'\u00e9quipement est principalement utilis\u00e9 pour le levage de cargaisons et la livraison de marchandises, les op\u00e9rations en haute altitude.<\/p>\r\n<p>2.un \u00e9quipement id\u00e9al pour un fonctionnement s\u00fbr<\/p>\r\n<p>3. elle se caract\u00e9rise par une grande capacit\u00e9 de chargement.<\/p>\r\n<p>4. ascension et descente constantes<\/p>\r\n<p>Le nouveau syst\u00e8me hydraulique augmente la s\u00e9curit\u00e9 et prot\u00e8ge les marchandises<\/p>\r\n<p>Mobile pratique, facile \u00e0 utiliser.<\/p>\r\n<p>7. l'\u00e9conomie et la praticabilit\u00e9.<\/p>","protected":false},"excerpt":{"rendered":"Nacelle \u00e9l\u00e9vatrice \u00e0 ciseaux sur chenilles (nacelle \u00e9l\u00e9vatrice \u00e0 ciseaux tout-terrain) : la nacelle \u00e9l\u00e9vatrice \u00e0 ciseaux autopropuls\u00e9e sur chenilles peut \u00eatre d\u00e9plac\u00e9e et utilis\u00e9e sur la surface de la table en \u00e9tat de levage, et le fonctionnement et l&#39;utilisation sont plus pratiques et flexibles. Une seule personne peut faire fonctionner la machine pour effectuer le levage, l&#39;avancement, le recul, le pilotage, etc. \u00e0 haute altitude [\u2026]","protected":false},"author":2,"featured_media":595,"parent":523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/posts\/594"}],"collection":[{"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/comments?post=594"}],"version-history":[{"count":1,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/posts\/594\/revisions"}],"predecessor-version":[{"id":596,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/posts\/594\/revisions\/596"}],"up":[{"embeddable":true,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/posts\/523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/media\/595"}],"wp:attachment":[{"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/media?parent=594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/categories?post=594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dfhydraulicscissorlift.com\/fr\/wp-json\/wp\/v2\/tags?post=594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}